{"id":171,"date":"2023-05-24T07:48:17","date_gmt":"2023-05-24T07:48:17","guid":{"rendered":"http:\/\/ciudadconalma.es\/madrid\/?page_id=171"},"modified":"2023-05-30T08:56:06","modified_gmt":"2023-05-30T08:56:06","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/ciudadconalma.es\/madrid\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<p>En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico le informamos de que este sitio web, al igual que la mayor\u00eda de los sitios en Internet, usa Cookies para mejorar y optimizar la experiencia del usuario. A continuaci\u00f3n encontrar\u00e1 informaci\u00f3n detallada sobre qu\u00e9 son las \u201cCookies\u201d, qu\u00e9 tipolog\u00eda utiliza este sitio web, c\u00f3mo cambiar la configuraci\u00f3n de sus cookies, y qu\u00e9 ocurre si deshabilita las Cookies.<\/p>\n<p><strong>\u00bfQu\u00e9 son las cookies?<\/strong><br \/>\nEs un fichero que se descarga en su ordenador, smartphone o dispositivo al acceder a una web. Las cookies permiten a la web almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n del usuario o del equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/p>\n<p><strong>Tipos de cookies seg\u00fan la entidad que las gestiona:<\/strong><\/p>\n<p>Propias: Las que se env\u00edan a su equipo, desde un equipo o dominio gestionado por el propio titular de la web y desde el que se presta el servicio solicitado por el usuario.<br \/>\nDe Tercero: Se env\u00edan a su equipo cuando navegas por nuestra web, pero desde un equipo o dominio que es<br \/>\ngestionado por un tercero. Si el tercero trata usa los datos obtenidos para sus propios fines, te avisaremos de ellas.<\/p>\n<p><strong>Tipos de cookies seg\u00fan el tiempo que permanecen en el equipo:<\/strong><\/p>\n<p>\u2022 De sesi\u00f3n: Activas cuando se accede a la web, desaparecen al fin de la sesi\u00f3n (ej. lista de productos comprados).<br \/>\n\u2022 Cookies persistentes: Los datos se quedan almacenados en el terminal y puede accederse y tratarse durante el<br \/>\nperiodo definido en la cookie, incluso a\u00f1os. Si podemos reduciremos al m\u00ednimo su duraci\u00f3n, seg\u00fan su finalidad.<\/p>\n<p><strong>Tipos de cookies seg\u00fan su finalidad:<\/strong><\/p>\n<p>\u2022 Funcionales y T\u00e9cnicas: Si s\u00f3lo prestan el servicio solicitado, no han que cumplir con la LSSI. Son las estrictamente necesarias para la gesti\u00f3n y operativa de la web, y para los servicios solicitados expresamente por el usuario, si se desactivan estas cookies, no recibir\u00e1 correctamente nuestros contenidos o servicios. Ejemplos:<br \/>\nControl del tr\u00e1fico y comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceso a partes restringidas, recordar el pedido del carrito de compra, realizar compras, gestionar pagos, prevenir fraudes, facilitar inscripciones o participaciones a eventos, contar visitas para facturar el software seg\u00fan el no de usos, usar elementos de seguridad al navegar, guardar datos de los v\u00eddeos o sonidos, habilitar contenidos din\u00e1micos (ej. animaci\u00f3n de carga de texto o imagen), compartir contenidos a trav\u00e9s de redes sociales; o gestionar los espacios publicitarios en base a criterios como el contenido editado, sin que se recopile informaci\u00f3n de los usuarios con otros fines (ej. personalizar los contenidos).<\/p>\n<p>\u2022 De Preferencias o personalizaci\u00f3n: Si elige caracter\u00edsticas (ej. si marcas la bandera del idioma de la web) no han<br \/>\nque cumplir con la LSSI, al considerarse un servicio expresamente solicitado. Permiten recordar las preferencias del usuario, como el idioma, el no de resultados a mostrar cuando hace una b\u00fasqueda, el aspecto o contenido del servicio seg\u00fan el navegador o la regi\u00f3n desde la que accedes, etc.<\/p>\n<p>\u2022 De entrada del usuario: Excluidas de la aplicaci\u00f3n de la LSSI. Rastrean al usuario al rellenar los formularios en l\u00ednea en varias p\u00e1ginas, o como cesta de la compra para seguir los art\u00edculos que haya seleccionado al pulsar un bot\u00f3n.<\/p>\n<p>\u2022 De autenticaci\u00f3n o identificaci\u00f3n de usuario (de sesi\u00f3n). Excluidas de la aplicaci\u00f3n de la LSSI.<\/p>\n<p>\u2022 De seguridad: Excluidas de la aplicaci\u00f3n de la LSSI. Detectan intentos err\u00f3neos o reiterados de conexi\u00f3n a la web.<\/p>\n<p>\u2022 Del reproductor multimedia, de equilibrio de carga; o de personalizaci\u00f3n de la interfaz del usuario. Excluidas de la aplicaci\u00f3n de la LSSI.<\/p>\n<p>\u2022 De complemento (plug-in) o sociales. Excluidas de la LSSI s\u00f3lo para el usuario con la sesi\u00f3n abierta. Controlan la interacci\u00f3n con las redes sociales dentro de la web. Se usan en \u201cyoutube\u201d, \u201cfacebook\u201d, \u201cgoogle\u201d y \u201ctwitter\u201d, u otros.<\/p>\n<p>\u2022 Cookies de an\u00e1lisis o medici\u00f3n: Debemos obtener un consentimiento informado aunque es poco probable que<br \/>\nrepresenten un riesgo para su privacidad si son de de primera parte y que tratan datos agregados para estad\u00edstica.<\/p>\n<p>Tratadas por nosotros o por terceros, permiten cuantificar el n.o de usuario, medir y analizar el comportamiento que se hace de la web, o contar las impresiones en pantalla o los clics en los anuncios para medir el rendimiento y mejorar la oferta de productos o servicios que ofrecemos.<\/p>\n<p>\u2022 Cookies publicitarias: Tratadas por nosotros o terceros, permiten gestionar la oferta de los espacios publicitarios que hay en la p\u00e1gina web, adecuando el contenido del anuncio al contenido del servicio solicitado, al uso que se realice de la web, o a la informaci\u00f3n que dispongamos sobre sus h\u00e1bitos de navegaci\u00f3n en Internet.<\/p>\n<p><strong>Otras formas de almacenamiento similar a las cookies<\/strong><\/p>\n<p>\u2022 LocalStorage y SessionStorage de HTML5: Espacio que la web puede usar en el equipo del usuario. Normalmente borrando el historial de Navegaci\u00f3n se pueden borrar.<br \/>\n\u2022 Local Shared Objects de Flash: Guardan m\u00e1s informaci\u00f3n que una cookie, y son independientes al navegador usado y m\u00e1s dif\u00edciles de localizar, visualizar o borrar. Pueden incluso regenerar cookies est\u00e1ndar. Un ejemplo es el Isolated storage Silverlight, hay que entrar en la carpeta de Microsoft del usuario para borrarlo. (Ej. video de vimeo).<br \/>\n\u2022 Web beacons o bugs: Son im\u00e1genes de tama\u00f1o m\u00ednimo, camufladas en la web e inapreciables a la vista. Se<br \/>\ndescargan al visitar la web pero que est\u00e1n almacenadas en un segundo sitio desde el que se registra la visita mediante la informaci\u00f3n que el navegador proporciona al descargar la imagen: direcci\u00f3n IP, sistema operativo, navegador, no de veces y horarios en los que se descarga la imagen.<\/p>\n<p><strong>Cookies que utiliza esta web https:\/\/www.ciudadconalma.com<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>NOMBRE<\/td>\n<td>DESCRIPCION\/FINALIDAD<\/td>\n<td>PROVEEDOR<\/td>\n<td>CADUCIDAD<\/td>\n<\/tr>\n<tr>\n<td>_ga<\/td>\n<td>Anal\u00edtica. Se usa para distinguir a los usuarios.<\/td>\n<td>Propia<\/td>\n<td>Fin sesi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>_gat<\/td>\n<td>Anal\u00edtica. Diferencia entre los diferentes objetos de seguimiento creados en la sesi\u00f3n.<\/td>\n<td>Propia<\/td>\n<td>10 minutos<\/td>\n<\/tr>\n<tr>\n<td>_gid<\/td>\n<td>Anal\u00edtica. Distingue a los usuarios<\/td>\n<td>Propia<\/td>\n<td>1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td>APISID<\/td>\n<td>Funcional.<\/td>\n<td>youtube<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>HSID<\/td>\n<td>Funcional.<\/td>\n<td>youtube<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>SID<\/td>\n<td>Funcional.<\/td>\n<td>youtube<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>LOGIN_INFO<\/td>\n<td>Funcional.<\/td>\n<td>youtube<\/td>\n<td>sesi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>PREF<\/td>\n<td>Funcional.<\/td>\n<td>youtube<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>VISITOR_INFO1_LIVE<\/td>\n<td>Anal\u00edtica. Intenta calcular el ancho de banda del usuario<\/td>\n<td>youtube<\/td>\n<td>179 dias<\/td>\n<\/tr>\n<tr>\n<td>YSC<\/td>\n<td>Anal\u00edtica. Registra una identificaci\u00f3n \u00fanica para saber que v\u00eddeos ha visto el usuario<\/td>\n<td>youtube<\/td>\n<td>sesi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>viewed_cookie_policy<\/td>\n<td>Funcional. Cookie necesaria para el funcionamiento de la visualizaci\u00f3n de cookies<\/td>\n<td>wordpress<\/td>\n<td>1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td>CONSENT<\/td>\n<td>Publicitaria. Mejora la publicidad, suele utilizarse para orientarse al usuario<\/td>\n<td>Google<\/td>\n<td>Persistente<\/td>\n<\/tr>\n<tr>\n<td>SIDCC<\/td>\n<td>Anal\u00edtica. Provee servicios y extrae informaci\u00f3n an\u00f3nima sobre la navegaci\u00f3n<\/td>\n<td>Google<\/td>\n<td>3 meses<\/td>\n<\/tr>\n<tr>\n<td>PHPSESSID<\/td>\n<td>Funcional. Usada por el lenguaje de encriptado PHP para que se guarden las<\/p>\n<p>variables de sesi\u00f3n<\/td>\n<td>Propia<\/td>\n<td>sesi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>DSID<\/td>\n<td>Publicitaria. Optimizaci\u00f3n de publicidad<\/td>\n<td>doubleclick<\/td>\n<td>15 dias<\/td>\n<\/tr>\n<tr>\n<td>IDE<\/td>\n<td>Publicitaria. Optimizaci\u00f3n de publicidad<\/td>\n<td>doubleclick<\/td>\n<td>1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td>SAPISID<\/td>\n<td>Publicitaria. Mide el rendimiento de los anuncios y proporciona recomendaciones<\/td>\n<td>Google<\/td>\n<td>Persistente<\/td>\n<\/tr>\n<tr>\n<td>SSID<\/td>\n<td>Publicitaria. Mide el rendimiento de los anuncios y proporciona recomendaciones<\/td>\n<td>Google<\/td>\n<td>Persistente<\/td>\n<\/tr>\n<tr>\n<td>__Secure-3PAPISID<\/td>\n<td>Publicitaria. Entrega anuncios m\u00e1s relevantes para usted y sus intereses<\/td>\n<td>Youtube<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>__Secure-3PSID<\/td>\n<td>Publicitaria. Entrega anuncios m\u00e1s relevantes para usted y sus intereses<\/td>\n<td>Google<\/td>\n<td>2 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td>__Secure-3PSIDCC<\/td>\n<td>Publicitaria. Muestran anuncios m\u00e1s relevantes para usted y sus gustos.<\/td>\n<td>Google<\/td>\n<td>1 d\u00eda<\/td>\n<\/tr>\n<tr>\n<td>SGPBShowingLimitation<br \/>\nDomain3834<\/td>\n<td>Anal\u00edticas. Controlar la frecuencia con la que se muestra al usuario una ventana<br \/>\nemergente para la suscripci\u00f3n al bolet\u00edn.<\/td>\n<td>Propia<\/td>\n<td>Permanente<\/td>\n<\/tr>\n<tr>\n<td>SGPBShowingLimitation<br \/>\nHomePage3834<\/td>\n<td>Anal\u00edticas. Controlar la frecuencia con la que se muestra al usuario una ventana<br \/>\nemergente para la suscripci\u00f3n al bolet\u00edn<\/td>\n<td>Propia<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 ocurre si se deshabilitan las Cookies?<\/strong><br \/>\nAlgunas funcionalidades de servicio, o \u00e1reas de la web podr\u00edan no funcionar correctamente. El no aceptar cookies conlleva instalar en su equipo una cookie de rechazo, que nos informa que no desea cookies en las sucesivas visitas.<\/p>\n<p><strong>\u00bfActualizamos nuestra Pol\u00edtica de Cookies?<\/strong><br \/>\nEs posible, por ello le recomendamos revisar esta pol\u00edtica cada vez que acceda a nuestro sitio web con el objetivo de estar adecuadamente informado sobre c\u00f3mo y para qu\u00e9 usamos las cookies.<\/p>\n<p><strong>\u00bfC\u00f3mo puede configurar sus Cookies?<\/strong><br \/>\nDesde el banner que le aparece al acceder a la web, tiene la posibilidad de ejercer su derecho a bloquear, eliminar y rechazar el uso de Cookies. Tambi\u00e9n puede modificando las opciones de su navegador.<\/p>\n<ul>\n<li>Microsoft Edge : Configuraci\u00f3n &gt; Configuraci\u00f3n avanzada &gt; Privacidad y servicios &gt; Cookies.<br \/>\nM\u00e1s informaci\u00f3n, consulte el soporte de Microsoft o la Ayuda del navegador.<\/li>\n<li>Mozilla Firefox: Herramientas &gt; Opciones &gt; Privacidad &gt; Historial &gt; Configuraci\u00f3n Personalizada.<br \/>\nM\u00e1s informaci\u00f3n, consulte el soporte de Mozilla o la Ayuda del navegador.<\/li>\n<li>Google Chrome: Configuraci\u00f3n &gt; Mostrar opciones avanzadas &gt; Privacidad &gt; Configuraci\u00f3n de contenido.<br \/>\nM\u00e1s informaci\u00f3n, consulte el soporte de Google o la Ayuda del navegador.<\/li>\n<li>Safari (Apple): Preferencias &gt; Seguridad.<br \/>\nM\u00e1s informaci\u00f3n, consulte el soporte de Apple o la Ayuda del navegador.<\/li>\n<li>Opera (Opera Software): Configuraci\u00f3n &gt; Opciones &gt; Avanzado &gt; Cookies<br \/>\nM\u00e1s informaci\u00f3n, consulte el soporte de Opera o la Ayuda del navegador.<\/li>\n<\/ul>\n<p>Si usa otro navegador distinto a los anteriores, consulte su pol\u00edtica de instalaci\u00f3n, uso y bloqueo de cookies.<br \/>\nOpciones para deshabilitar cookies y opt-out.<br \/>\nUsando la herramienta <a href=\"http:\/\/www.youronlinechoices.com\" target=\"_blank\" rel=\"noopener\">www.youronlinechoices.com<\/a>, podr\u00e1 encontrar informaci\u00f3n \u00fatil y configurar, proveedor por<br \/>\nproveedor, sus preferencias sobre las cookies.<br \/>\nHay herramientas de terceros, que permiten a los usuarios detectar las cookies de cada sitio web que visita y gestionar su desactivaci\u00f3n. Por ejemplo, Ghostery: <a href=\"http:\/\/www.ghostery.com\/privacy-statement\" target=\"_blank\" rel=\"noopener\">http:\/\/www.ghostery.com\/privacy-statement<\/a><\/p>\n<p>Existe un complemento para desactivar las cookies de Google Analytics: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=es\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=es<\/a><br \/>\nExiste una opci\u00f3n para deshabilitar cookies publicitarias, de todas las empresas suscritas a la NAI (Network advertising iniciative): <a href=\"https:\/\/optout.networkadvertising.org\/?c=1\" target=\"_blank\" rel=\"noopener\">https:\/\/optout.networkadvertising.org\/?c=1<\/a><br \/>\nPuedes consultar m\u00e1s informaci\u00f3n sobre cookies en https:\/\/www.aboutcookies.org\/ y en <a href=\"https:\/\/www.allaboutcookies.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.allaboutcookies.org\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico le informamos de que este sitio web, al igual que la mayor\u00eda de los sitios en Internet, usa Cookies para mejorar y optimizar la experiencia del usuario. A continuaci\u00f3n encontrar\u00e1 informaci\u00f3n detallada sobre qu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/pages\/171"}],"collection":[{"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":2,"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":176,"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/pages\/171\/revisions\/176"}],"wp:attachment":[{"href":"https:\/\/ciudadconalma.es\/madrid\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}